{"id":988671,"date":"2022-07-10T17:00:57","date_gmt":"2022-07-10T15:00:57","guid":{"rendered":"https:\/\/www.wanda-collection.com\/blog\/?p=988671"},"modified":"2026-08-31T16:58:28","modified_gmt":"2026-08-31T14:58:28","slug":"les-vasques-florence-une-collection-salle-de-bain-a-decouvrir","status":"publish","type":"post","link":"https:\/\/www.wanda-collection.com\/blog\/les-vasques-florence-une-collection-salle-de-bain-a-decouvrir\/","title":{"rendered":"Les vasques Florence\u00a0: une collection salle de bain \u00e0 d\u00e9couvrir"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"988671\" class=\"elementor elementor-988671\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-126037c8 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"126037c8\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-71489832\" data-id=\"71489832\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-294ecdd elementor-widget elementor-widget-heading\" data-id=\"294ecdd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pourquoi craquer pour la collection salle de bain Florence ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-344a2d8f elementor-drop-cap-yes elementor-widget-mobile__width-inherit elementor-drop-cap-view-default elementor-widget elementor-widget-text-editor\" data-id=\"344a2d8f\" data-element_type=\"widget\" data-settings=\"{&quot;drop_cap&quot;:&quot;yes&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vous cherchez des meubles de salle de bain qui allient un design moderne \u00e0 des mat\u00e9riaux de qualit\u00e9\u00a0? La collection Florence propose une s\u00e9rie de vasques et de meubles vasques fabriqu\u00e9es en marbre et en teck. Au programme\u00a0: des mati\u00e8res nobles et des lignes \u00e9pur\u00e9es, pour une collection salle de bain unique sign\u00e9e Wanda Collection.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-237307d2 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"237307d2\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-541d8cbe\" data-id=\"541d8cbe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-32c1185a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"32c1185a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2ef762be\" data-id=\"2ef762be\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73e236bd elementor-widget elementor-widget-heading\" data-id=\"73e236bd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Des lignes modernes et \u00e9pur\u00e9es<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-110ef766 elementor-widget elementor-widget-text-editor\" data-id=\"110ef766\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La collection Florence, c\u2019est avant tout un design qui marque les esprits. Les vasques en marbre adoptent une forme unique \u00e0 la modernit\u00e9 redoutable. Elles apporteront du caract\u00e8re \u00e0 n\u2019importe quelle pi\u00e8ce d\u2019eau\u00a0! De leur c\u00f4t\u00e9, les meubles vasques soulignent les courbes de la vasque, prolongeant ses lignes rondes et \u00e9l\u00e9gantes. Ils offrent un espace de rangement important sans alt\u00e9rer le style de votre espace.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-31ac75fa\" data-id=\"31ac75fa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6b1efaac elementor-hidden-mobile elementor-hidden-tablet\" data-id=\"6b1efaac\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-31226991 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"31226991\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3ad5f94f\" data-id=\"3ad5f94f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f6ec82 elementor-widget elementor-widget-heading\" data-id=\"1f6ec82\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Le teck \u00e0 l\u2019honneur dans la salle de bain<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f14ad30 elementor-widget elementor-widget-text-editor\" data-id=\"1f14ad30\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tout droit venu d\u2019Indon\u00e9sie, le teck se range parmi les bois exotiques. Ses reflets cuivr\u00e9s apportent une ambiance zen et chaleureuse\u2026 Mais surtout, il s\u2019agit d\u2019une essence naturellement imputrescible. Sa r\u00e9sistance \u00e0 l\u2019humidit\u00e9 est une propri\u00e9t\u00e9 id\u00e9ale pour am\u00e9nager une pi\u00e8ce humide. C\u2019est pourquoi Wanda Collection a choisi le teck pour concevoir l\u2019ensemble de son mobilier de salle de bain\u00a0! Et la collection Florence ne d\u00e9roge pas \u00e0 la r\u00e8gle.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-70182c1 elementor-widget elementor-widget-image\" data-id=\"70182c1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.wanda-collection.com\/art-meuble-sous-vasque-en-teck-florence-120cm-vasque-noir-2941.htm\">\n\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"555\" height=\"555\" src=\"https:\/\/www.wanda-collection.com\/blog\/wp-content\/uploads\/2022\/08\/ori-meuble-sous-vasque-en-teck-florence-120cm-vasque-noir-2941_2692.jpg\" class=\"attachment-large size-large wp-image-989439\" alt=\"\" srcset=\"https:\/\/www.wanda-collection.com\/blog\/wp-content\/uploads\/2022\/08\/ori-meuble-sous-vasque-en-teck-florence-120cm-vasque-noir-2941_2692.jpg 555w, https:\/\/www.wanda-collection.com\/blog\/wp-content\/uploads\/2022\/08\/ori-meuble-sous-vasque-en-teck-florence-120cm-vasque-noir-2941_2692-300x300.jpg 300w, https:\/\/www.wanda-collection.com\/blog\/wp-content\/uploads\/2022\/08\/ori-meuble-sous-vasque-en-teck-florence-120cm-vasque-noir-2941_2692-150x150.jpg 150w\" sizes=\"(max-width: 555px) 100vw, 555px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-30abe90 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"30abe90\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3030efc\" data-id=\"3030efc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b1ebfdc elementor-widget elementor-widget-heading\" data-id=\"b1ebfdc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">D\u00e9couvrez les pi\u00e8ces de la collection Florence<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f511899 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f511899\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1127661\" data-id=\"1127661\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f13d7ca elementor-widget elementor-widget-spacer\" data-id=\"f13d7ca\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-348e38e4 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"348e38e4\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-15a76e1b\" data-id=\"15a76e1b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d7be552 elementor-widget elementor-widget-heading\" data-id=\"d7be552\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">La vasque sur pied Florence<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b419b0 elementor-widget elementor-widget-text-editor\" data-id=\"5b419b0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La vasque en marbre Florence se reconna\u00eet du premier coup d\u2019\u0153il gr\u00e2ce \u00e0 sa forme conique. Elle dispose d\u2019un bol lisse et d\u2019un pied brut\u00a0: ce m\u00e9lange de textures offre un rendu sophistiqu\u00e9, id\u00e9al pour am\u00e9nager une salle de bain contemporaine.<\/p><p>Disponible en marbre gris, noir ou cr\u00e8me, la vasque Florence se distingue par sa grande qualit\u00e9. Elle se marie parfaitement au meuble vasque de la collection. Une association choc pour ceux qui souhaitent ajouter des rangements \u00e0 leur salle d\u2019eau.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a4b02c2 elementor-widget elementor-widget-spacer\" data-id=\"a4b02c2\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-14106209 elementor-widget elementor-widget-image\" data-id=\"14106209\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.wanda-collection.com\/art-meuble-de-salle-de-bain-en-teck-florence-120cm-vasque-creme-2939.htm\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"544\" height=\"544\" src=\"https:\/\/www.wanda-collection.com\/blog\/wp-content\/uploads\/2022\/08\/ar-meuble-de-salle-de-bain-en-teck-florence-120cm-vasque-creme-2939-1.jpg\" class=\"attachment-full size-full wp-image-989441\" alt=\"\" srcset=\"https:\/\/www.wanda-collection.com\/blog\/wp-content\/uploads\/2022\/08\/ar-meuble-de-salle-de-bain-en-teck-florence-120cm-vasque-creme-2939-1.jpg 544w, https:\/\/www.wanda-collection.com\/blog\/wp-content\/uploads\/2022\/08\/ar-meuble-de-salle-de-bain-en-teck-florence-120cm-vasque-creme-2939-1-300x300.jpg 300w, https:\/\/www.wanda-collection.com\/blog\/wp-content\/uploads\/2022\/08\/ar-meuble-de-salle-de-bain-en-teck-florence-120cm-vasque-creme-2939-1-150x150.jpg 150w\" sizes=\"(max-width: 544px) 100vw, 544px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-755bbece\" data-id=\"755bbece\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-12f86bc2 elementor-widget elementor-widget-image\" data-id=\"12f86bc2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.wanda-collection.com\/art-vasque-salle-de-bain-sur-pied-en-marbre-florence-gris-580.htm\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"555\" height=\"555\" src=\"https:\/\/www.wanda-collection.com\/blog\/wp-content\/uploads\/2022\/10\/31005.jpg\" class=\"attachment-full size-full wp-image-988678\" alt=\"\" srcset=\"https:\/\/www.wanda-collection.com\/blog\/wp-content\/uploads\/2022\/10\/31005.jpg 555w, https:\/\/www.wanda-collection.com\/blog\/wp-content\/uploads\/2022\/10\/31005-300x300.jpg 300w, https:\/\/www.wanda-collection.com\/blog\/wp-content\/uploads\/2022\/10\/31005-150x150.jpg 150w\" sizes=\"(max-width: 555px) 100vw, 555px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9570824 elementor-widget elementor-widget-spacer\" data-id=\"9570824\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d1188d7 elementor-widget elementor-widget-heading\" data-id=\"d1188d7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Le meuble simple vasque Florence<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba00de3 elementor-widget elementor-widget-text-editor\" data-id=\"ba00de3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le meuble vasque Florence \u00e9pouse parfaitement les courbes de la vasque (livr\u00e9e avec). Il est fabriqu\u00e9 enti\u00e8rement en teck massif, ce qui lui permet non seulement de r\u00e9chauffer l\u2019aspect froid du marbre, mais aussi de b\u00e9n\u00e9ficier des propri\u00e9t\u00e9s exceptionnelles de ce bois exotique. En effet, le teck r\u00e9siste \u00e0 l\u2019humidit\u00e9, est facile \u00e0 entretenir et dure longtemps.<\/p><p>Le meuble de salle de bain Florence offre un espace de rangement optimal gr\u00e2ce \u00e0 ses 6 \u00e9tag\u00e8res. Il s\u2019associera parfaitement aux autres produits en teck sign\u00e9s Wanda Collection.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a31fbd5 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a31fbd5\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7c1de639\" data-id=\"7c1de639\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af1089e elementor-widget elementor-widget-heading\" data-id=\"af1089e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Le meuble double vasque Florence<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ccd3f34 elementor-widget elementor-widget-text-editor\" data-id=\"6ccd3f34\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vous avez une famille nombreuse\u00a0? L\u2019installation d\u2019un meuble double vasque vous permettra de gagner du temps lors de l\u2019utilisation de votre salle de bain. C\u2019est pourquoi le meuble sous vasque Florence se d\u00e9cline en version double vasque\u00a0! Esth\u00e9tique et solide, il comprend 9 \u00e9tag\u00e8res\u00a0: de quoi ranger les affaires de toilette de toute la famille.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-8f428bd elementor-widget elementor-widget-image\" data-id=\"8f428bd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.wanda-collection.com\/art-meuble-sous-vasque-en-teck-florence-double-180cm-vasques-noir-2945.htm\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"555\" height=\"555\" src=\"https:\/\/www.wanda-collection.com\/blog\/wp-content\/uploads\/2022\/08\/ar-meuble-sous-vasque-en-teck-florence-double-180cm-vasques-noir-2945.jpg\" class=\"attachment-large size-large wp-image-989440\" alt=\"\" srcset=\"https:\/\/www.wanda-collection.com\/blog\/wp-content\/uploads\/2022\/08\/ar-meuble-sous-vasque-en-teck-florence-double-180cm-vasques-noir-2945.jpg 555w, https:\/\/www.wanda-collection.com\/blog\/wp-content\/uploads\/2022\/08\/ar-meuble-sous-vasque-en-teck-florence-double-180cm-vasques-noir-2945-300x300.jpg 300w, https:\/\/www.wanda-collection.com\/blog\/wp-content\/uploads\/2022\/08\/ar-meuble-sous-vasque-en-teck-florence-double-180cm-vasques-noir-2945-150x150.jpg 150w\" sizes=\"(max-width: 555px) 100vw, 555px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6bcba301 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6bcba301\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3b048fb1\" data-id=\"3b048fb1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-97271a0 elementor-widget elementor-widget-text-editor\" data-id=\"97271a0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Si vous avez besoin de meubles de rangement suppl\u00e9mentaires, vous pouvez consulter le catalogue Wanda Collection. Vous trouverez de nombreux produits en teck de conception artisanale, qui allient un design soign\u00e9 \u00e0 des performances optimales.<\/p>\n<!-- wanda-maillage-2026-08 --><div style=\"background:#faf6ef; border-left:4px solid #d4a84b; padding:24px 28px; margin:32px 0; border-radius:0 8px 8px 0;\"><p style=\"color:#1a1a2e; font-size:1.15em; margin:0 0 14px; font-weight:600; letter-spacing:0.3px; text-transform:uppercase;\">\u00c0 lire aussi sur le blog Wanda<\/p><ul style=\"margin:0; padding:0 0 0 18px; line-height:1.9;\"><li><a href=\"https:\/\/www.wanda-collection.com\/blog\/pourquoi-choisir-une-vasque-en-pierre-naturelle-guide-complet\/\" style=\"font-weight:700; text-decoration:underline; color:#1a1a2e;\"><strong>Vasque en pierre naturelle : guide complet<\/strong><\/a><\/li><li><a href=\"https:\/\/www.wanda-collection.com\/blog\/colonne-salle-de-bain-bois\/\" style=\"font-weight:700; text-decoration:underline; color:#1a1a2e;\"><strong>Colonne de salle de bain en bois : hauteur et fixation<\/strong><\/a><\/li><li><a href=\"https:\/\/www.wanda-collection.com\/blog\/vasque-en-terrazzo\/\" style=\"font-weight:700; text-decoration:underline; color:#1a1a2e;\"><strong>Vasque en terrazzo : \u00e9l\u00e9gance min\u00e9rale<\/strong><\/a><\/li><\/ul><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La collection Florence, c\u2019est avant tout un design qui marque les esprits. Les vasques en marbre adoptent une forme unique \u00e0 la modernit\u00e9 redoutable. Elles apporteront du caract\u00e8re \u00e0 n\u2019importe quelle pi\u00e8ce d\u2019eau ! <\/p>\n","protected":false},"author":2,"featured_media":989442,"comment_status":"closed","ping_status":"open","sticky":false,"template":"elementor_theme","format":"standard","meta":{"footnotes":""},"categories":[113,101],"tags":[],"class_list":["post-988671","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tendances-deco","category-vasques"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les vasques Florence\u00a0: une collection salle de bain \u00e0 d\u00e9couvrir<\/title>\n<meta name=\"description\" content=\"La collection Florence, c\u2019est avant tout un design qui marque les esprits. Les vasques en marbre adoptent une forme unique \u00e0 la modernit\u00e9 redoutable. Elles apporteront du caract\u00e8re \u00e0 n\u2019importe quelle pi\u00e8ce d\u2019eau !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wanda-collection.com\/blog\/les-vasques-florence-une-collection-salle-de-bain-a-decouvrir\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les vasques Florence\u00a0: une collection salle de bain \u00e0 d\u00e9couvrir\" \/>\n<meta property=\"og:description\" content=\"La collection Florence, c\u2019est avant tout un design qui marque les esprits. Les vasques en marbre adoptent une forme unique \u00e0 la modernit\u00e9 redoutable. Elles apporteront du caract\u00e8re \u00e0 n\u2019importe quelle pi\u00e8ce d\u2019eau !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wanda-collection.com\/blog\/les-vasques-florence-une-collection-salle-de-bain-a-decouvrir\/\" \/>\n<meta property=\"og:site_name\" content=\"Wanda collection Le blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WandaCollection.fr\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-10T15:00:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-31T14:58:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.wanda-collection.com\/blog\/wp-content\/uploads\/2022\/08\/31003C-11.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"555\" \/>\n\t<meta property=\"og:image:height\" content=\"555\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"David\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.wanda-collection.com\/blog\/les-vasques-florence-une-collection-salle-de-bain-a-decouvrir\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.wanda-collection.com\/blog\/les-vasques-florence-une-collection-salle-de-bain-a-decouvrir\/\"},\"author\":{\"name\":\"David\",\"@id\":\"https:\/\/www.wanda-collection.com\/blog\/#\/schema\/person\/173d78a9973ea0be9b1bff2a7d0ac370\"},\"headline\":\"Les vasques Florence\u00a0: une collection salle de bain \u00e0 d\u00e9couvrir\",\"datePublished\":\"2022-07-10T15:00:57+00:00\",\"dateModified\":\"2026-08-31T14:58:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.wanda-collection.com\/blog\/les-vasques-florence-une-collection-salle-de-bain-a-decouvrir\/\"},\"wordCount\":561,\"publisher\":{\"@id\":\"https:\/\/www.wanda-collection.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.wanda-collection.com\/blog\/les-vasques-florence-une-collection-salle-de-bain-a-decouvrir\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.wanda-collection.com\/blog\/wp-content\/uploads\/2022\/08\/31003C-11.jpg\",\"articleSection\":[\"Tendances d\u00e9co\",\"Vasques\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.wanda-collection.com\/blog\/les-vasques-florence-une-collection-salle-de-bain-a-decouvrir\/\",\"url\":\"https:\/\/www.wanda-collection.com\/blog\/les-vasques-florence-une-collection-salle-de-bain-a-decouvrir\/\",\"name\":\"Les vasques Florence\u00a0: une collection salle de bain \u00e0 d\u00e9couvrir\",\"isPartOf\":{\"@id\":\"https:\/\/www.wanda-collection.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.wanda-collection.com\/blog\/les-vasques-florence-une-collection-salle-de-bain-a-decouvrir\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.wanda-collection.com\/blog\/les-vasques-florence-une-collection-salle-de-bain-a-decouvrir\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.wanda-collection.com\/blog\/wp-content\/uploads\/2022\/08\/31003C-11.jpg\",\"datePublished\":\"2022-07-10T15:00:57+00:00\",\"dateModified\":\"2026-08-31T14:58:28+00:00\",\"description\":\"La collection Florence, c\u2019est avant tout un design qui marque les esprits. Les vasques en marbre adoptent une forme unique \u00e0 la modernit\u00e9 redoutable. Elles apporteront du caract\u00e8re \u00e0 n\u2019importe quelle pi\u00e8ce d\u2019eau !\",\"breadcrumb\":{\"@id\":\"https:\/\/www.wanda-collection.com\/blog\/les-vasques-florence-une-collection-salle-de-bain-a-decouvrir\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.wanda-collection.com\/blog\/les-vasques-florence-une-collection-salle-de-bain-a-decouvrir\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.wanda-collection.com\/blog\/les-vasques-florence-une-collection-salle-de-bain-a-decouvrir\/#primaryimage\",\"url\":\"https:\/\/www.wanda-collection.com\/blog\/wp-content\/uploads\/2022\/08\/31003C-11.jpg\",\"contentUrl\":\"https:\/\/www.wanda-collection.com\/blog\/wp-content\/uploads\/2022\/08\/31003C-11.jpg\",\"width\":555,\"height\":555},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.wanda-collection.com\/blog\/les-vasques-florence-une-collection-salle-de-bain-a-decouvrir\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.wanda-collection.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Salle de bain\",\"item\":\"https:\/\/www.wanda-collection.com\/blog\/category\/salle-de-bain\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vasques\",\"item\":\"https:\/\/www.wanda-collection.com\/blog\/category\/salle-de-bain\/vasques\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Les vasques Florence\u00a0: une collection salle de bain \u00e0 d\u00e9couvrir\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.wanda-collection.com\/blog\/#website\",\"url\":\"https:\/\/www.wanda-collection.com\/blog\/\",\"name\":\"Wanda collection Le blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.wanda-collection.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.wanda-collection.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.wanda-collection.com\/blog\/#organization\",\"name\":\"Wanda collection Le blog\",\"url\":\"https:\/\/www.wanda-collection.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.wanda-collection.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.wanda-collection.com\/blog\/wp-content\/uploads\/2022\/09\/cropped-logo-Le-blog-5.png\",\"contentUrl\":\"https:\/\/www.wanda-collection.com\/blog\/wp-content\/uploads\/2022\/09\/cropped-logo-Le-blog-5.png\",\"width\":1141,\"height\":328,\"caption\":\"Wanda collection Le blog\"},\"image\":{\"@id\":\"https:\/\/www.wanda-collection.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/WandaCollection.fr\/\",\"https:\/\/www.pinterest.fr\/wandacollection\/\",\"https:\/\/www.instagram.com\/wanda.collection\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.wanda-collection.com\/blog\/#\/schema\/person\/173d78a9973ea0be9b1bff2a7d0ac370\",\"name\":\"David\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.wanda-collection.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9a07c287e9190bc6c95fa3ed42c95d09a7a2eebd3c4740b8a82ff624397988e3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9a07c287e9190bc6c95fa3ed42c95d09a7a2eebd3c4740b8a82ff624397988e3?s=96&d=mm&r=g\",\"caption\":\"David\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les vasques Florence\u00a0: une collection salle de bain \u00e0 d\u00e9couvrir","description":"La collection Florence, c\u2019est avant tout un design qui marque les esprits. Les vasques en marbre adoptent une forme unique \u00e0 la modernit\u00e9 redoutable. Elles apporteront du caract\u00e8re \u00e0 n\u2019importe quelle pi\u00e8ce d\u2019eau !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wanda-collection.com\/blog\/les-vasques-florence-une-collection-salle-de-bain-a-decouvrir\/","og_locale":"fr_FR","og_type":"article","og_title":"Les vasques Florence\u00a0: une collection salle de bain \u00e0 d\u00e9couvrir","og_description":"La collection Florence, c\u2019est avant tout un design qui marque les esprits. Les vasques en marbre adoptent une forme unique \u00e0 la modernit\u00e9 redoutable. Elles apporteront du caract\u00e8re \u00e0 n\u2019importe quelle pi\u00e8ce d\u2019eau !","og_url":"https:\/\/www.wanda-collection.com\/blog\/les-vasques-florence-une-collection-salle-de-bain-a-decouvrir\/","og_site_name":"Wanda collection Le blog","article_publisher":"https:\/\/www.facebook.com\/WandaCollection.fr\/","article_published_time":"2022-07-10T15:00:57+00:00","article_modified_time":"2026-08-31T14:58:28+00:00","og_image":[{"width":555,"height":555,"url":"https:\/\/www.wanda-collection.com\/blog\/wp-content\/uploads\/2022\/08\/31003C-11.jpg","type":"image\/jpeg"}],"author":"David","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"David","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.wanda-collection.com\/blog\/les-vasques-florence-une-collection-salle-de-bain-a-decouvrir\/#article","isPartOf":{"@id":"https:\/\/www.wanda-collection.com\/blog\/les-vasques-florence-une-collection-salle-de-bain-a-decouvrir\/"},"author":{"name":"David","@id":"https:\/\/www.wanda-collection.com\/blog\/#\/schema\/person\/173d78a9973ea0be9b1bff2a7d0ac370"},"headline":"Les vasques Florence\u00a0: une collection salle de bain \u00e0 d\u00e9couvrir","datePublished":"2022-07-10T15:00:57+00:00","dateModified":"2026-08-31T14:58:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.wanda-collection.com\/blog\/les-vasques-florence-une-collection-salle-de-bain-a-decouvrir\/"},"wordCount":561,"publisher":{"@id":"https:\/\/www.wanda-collection.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.wanda-collection.com\/blog\/les-vasques-florence-une-collection-salle-de-bain-a-decouvrir\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wanda-collection.com\/blog\/wp-content\/uploads\/2022\/08\/31003C-11.jpg","articleSection":["Tendances d\u00e9co","Vasques"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.wanda-collection.com\/blog\/les-vasques-florence-une-collection-salle-de-bain-a-decouvrir\/","url":"https:\/\/www.wanda-collection.com\/blog\/les-vasques-florence-une-collection-salle-de-bain-a-decouvrir\/","name":"Les vasques Florence\u00a0: une collection salle de bain \u00e0 d\u00e9couvrir","isPartOf":{"@id":"https:\/\/www.wanda-collection.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.wanda-collection.com\/blog\/les-vasques-florence-une-collection-salle-de-bain-a-decouvrir\/#primaryimage"},"image":{"@id":"https:\/\/www.wanda-collection.com\/blog\/les-vasques-florence-une-collection-salle-de-bain-a-decouvrir\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wanda-collection.com\/blog\/wp-content\/uploads\/2022\/08\/31003C-11.jpg","datePublished":"2022-07-10T15:00:57+00:00","dateModified":"2026-08-31T14:58:28+00:00","description":"La collection Florence, c\u2019est avant tout un design qui marque les esprits. Les vasques en marbre adoptent une forme unique \u00e0 la modernit\u00e9 redoutable. Elles apporteront du caract\u00e8re \u00e0 n\u2019importe quelle pi\u00e8ce d\u2019eau !","breadcrumb":{"@id":"https:\/\/www.wanda-collection.com\/blog\/les-vasques-florence-une-collection-salle-de-bain-a-decouvrir\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wanda-collection.com\/blog\/les-vasques-florence-une-collection-salle-de-bain-a-decouvrir\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.wanda-collection.com\/blog\/les-vasques-florence-une-collection-salle-de-bain-a-decouvrir\/#primaryimage","url":"https:\/\/www.wanda-collection.com\/blog\/wp-content\/uploads\/2022\/08\/31003C-11.jpg","contentUrl":"https:\/\/www.wanda-collection.com\/blog\/wp-content\/uploads\/2022\/08\/31003C-11.jpg","width":555,"height":555},{"@type":"BreadcrumbList","@id":"https:\/\/www.wanda-collection.com\/blog\/les-vasques-florence-une-collection-salle-de-bain-a-decouvrir\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.wanda-collection.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Salle de bain","item":"https:\/\/www.wanda-collection.com\/blog\/category\/salle-de-bain\/"},{"@type":"ListItem","position":3,"name":"Vasques","item":"https:\/\/www.wanda-collection.com\/blog\/category\/salle-de-bain\/vasques\/"},{"@type":"ListItem","position":4,"name":"Les vasques Florence\u00a0: une collection salle de bain \u00e0 d\u00e9couvrir"}]},{"@type":"WebSite","@id":"https:\/\/www.wanda-collection.com\/blog\/#website","url":"https:\/\/www.wanda-collection.com\/blog\/","name":"Wanda collection Le blog","description":"","publisher":{"@id":"https:\/\/www.wanda-collection.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wanda-collection.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.wanda-collection.com\/blog\/#organization","name":"Wanda collection Le blog","url":"https:\/\/www.wanda-collection.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.wanda-collection.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.wanda-collection.com\/blog\/wp-content\/uploads\/2022\/09\/cropped-logo-Le-blog-5.png","contentUrl":"https:\/\/www.wanda-collection.com\/blog\/wp-content\/uploads\/2022\/09\/cropped-logo-Le-blog-5.png","width":1141,"height":328,"caption":"Wanda collection Le blog"},"image":{"@id":"https:\/\/www.wanda-collection.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WandaCollection.fr\/","https:\/\/www.pinterest.fr\/wandacollection\/","https:\/\/www.instagram.com\/wanda.collection\/"]},{"@type":"Person","@id":"https:\/\/www.wanda-collection.com\/blog\/#\/schema\/person\/173d78a9973ea0be9b1bff2a7d0ac370","name":"David","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.wanda-collection.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9a07c287e9190bc6c95fa3ed42c95d09a7a2eebd3c4740b8a82ff624397988e3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9a07c287e9190bc6c95fa3ed42c95d09a7a2eebd3c4740b8a82ff624397988e3?s=96&d=mm&r=g","caption":"David"}}]}},"_links":{"self":[{"href":"https:\/\/www.wanda-collection.com\/blog\/wp-json\/wp\/v2\/posts\/988671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wanda-collection.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wanda-collection.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wanda-collection.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wanda-collection.com\/blog\/wp-json\/wp\/v2\/comments?post=988671"}],"version-history":[{"count":18,"href":"https:\/\/www.wanda-collection.com\/blog\/wp-json\/wp\/v2\/posts\/988671\/revisions"}],"predecessor-version":[{"id":989446,"href":"https:\/\/www.wanda-collection.com\/blog\/wp-json\/wp\/v2\/posts\/988671\/revisions\/989446"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wanda-collection.com\/blog\/wp-json\/wp\/v2\/media\/989442"}],"wp:attachment":[{"href":"https:\/\/www.wanda-collection.com\/blog\/wp-json\/wp\/v2\/media?parent=988671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wanda-collection.com\/blog\/wp-json\/wp\/v2\/categories?post=988671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wanda-collection.com\/blog\/wp-json\/wp\/v2\/tags?post=988671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}